{"id":3153,"date":"2018-09-30T21:06:09","date_gmt":"2018-09-30T19:06:09","guid":{"rendered":"http:\/\/nmsernstbrunn.ac.at\/?p=3153"},"modified":"2019-08-26T09:01:37","modified_gmt":"2019-08-26T07:01:37","slug":"das-ende-eines-kapitels","status":"publish","type":"post","link":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/2018\/09\/das-ende-eines-kapitels\/","title":{"rendered":"Das Ende eines Kapitels"},"content":{"rendered":"<p><strong><span style=\"font-size: 14pt;\">Frau Margarete Piringer geht in den Ruhestand<\/span><\/strong><\/p>\n<p>Eine weitere verdienstvolle Lehrerpers\u00f6nlichkeit verl\u00e4sst unsere Schule und begibt sich in den Ruhestand. Frau Piringer hat durch ihr Engagement das Schulleben der \u00d6ko MS Ernstbrunn \u00fcber viele Jahre mitgepr\u00e4gt.<\/p>\n<p>In ihrem Unterricht schaffte sie es immer wieder die Kinder zu begeistern, ihre ber\u00fchmten Sagen und die spannenden Erz\u00e4hlungen aus der Geschichte fesselten die Sch\u00fcler und Sch\u00fclerinnen.<br \/>\nIn den letzten Jahren sorgte die vielseitige Lehrerin mit der &#8222;Darstellenden Spiel&#8220;-Gruppe f\u00fcr gelungene und stets gut besuchte Auftritte. Bei zahlreichen Lehrausg\u00e4ngen und Exkursionen\u00a0 gab sie die perfekte Reisef\u00fchrerin. Ein weiteres Highlight war der von ihr ins Leben gerufene Kinderflohmarkt. Und nicht zuletzt schuf Frau Piringer eine liebevoll eingerichtete, \u00e4u\u00dferst gut sortierte Schulbibliothek, wo sie Generationen von Kindern das Lesen schmackhaft machte &#8230;<\/p>\n<p>Wir m\u00f6chten uns an dieser Stelle herzlichst bedanken und w\u00fcnschen dir Alles Gute f\u00fcr die Zukunft und viel Gesundheit!<\/p>\n<p>&nbsp;<\/p>\n<p><a  href=\"http:\/\/nmsernstbrunn.ac.at\/wordpress\/wp-content\/uploads\/2018\/09\/20180928_095811.jpg\" data-rel=\"lightbox-gallery-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3154 aligncenter\" src=\"http:\/\/nmsernstbrunn.ac.at\/wordpress\/wp-content\/uploads\/2018\/09\/20180928_095811-600x338.jpg\" alt=\"\" width=\"600\" height=\"338\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frau Margarete Piringer geht in den Ruhestand Eine weitere verdienstvolle Lehrerpers\u00f6nlichkeit verl\u00e4sst unsere Schule und begibt sich in den Ruhestand. Frau Piringer hat durch ihr Engagement das Schulleben der \u00d6ko MS Ernstbrunn \u00fcber viele Jahre mitgepr\u00e4gt. In ihrem Unterricht schaffte sie es immer wieder die Kinder zu begeistern, ihre ber\u00fchmten [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3154,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-3153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archiv-2018-19"],"_links":{"self":[{"href":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-json\/wp\/v2\/posts\/3153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-json\/wp\/v2\/comments?post=3153"}],"version-history":[{"count":5,"href":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-json\/wp\/v2\/posts\/3153\/revisions"}],"predecessor-version":[{"id":3253,"href":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-json\/wp\/v2\/posts\/3153\/revisions\/3253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-json\/wp\/v2\/media\/3154"}],"wp:attachment":[{"href":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-json\/wp\/v2\/media?parent=3153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-json\/wp\/v2\/categories?post=3153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-json\/wp\/v2\/tags?post=3153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}