{"id":2771,"date":"2017-11-29T00:21:58","date_gmt":"2017-11-28T23:21:58","guid":{"rendered":"http:\/\/nmsernstbrunn.ac.at\/?p=2771"},"modified":"2018-08-31T13:21:42","modified_gmt":"2018-08-31T11:21:42","slug":"schulsport-guetesiegel-in-gold","status":"publish","type":"post","link":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/2017\/11\/schulsport-guetesiegel-in-gold\/","title":{"rendered":"Schulsport G\u00fctesiegel in GOLD"},"content":{"rendered":"<hr class=\"wc-shortcodes-spacing \" style=\"height: 15px\" \/>\n<p style=\"text-align: left;\"><span style=\"font-size: 18pt;\">Gro\u00dfe Ehre f\u00fcr die N\u00d6 \u00d6ko Mittelschule Ernstbrunn!<\/span><\/p>\n<p>Unsere Schule wurde vor kurzem mit dem <strong>Schulsportg\u00fctesiegel in Gold<\/strong> ausgezeichnet.<\/p>\n<p>Die Bem\u00fchungen im Bereich des Schulsports (Sommersportwochen, Wintersportwochen, Schwimmwoche, Ski4school-Tage, Tage des Sports, Volleyball, Fu\u00dfball, Fu\u00dfball-M\u00e4dchen, alle Aktivit\u00e4ten im Bewegungs- und Sportunterricht \u2013 Kletterpark, Eislaufen, Nordic Walking,\u2026..) haben somit eine verdiente W\u00fcrdigung erhalten.<\/p>\n<p>Die \u00dcberreichung der Urkunde wird demn\u00e4chst durch den Landesschulrat f\u00fcr N\u00d6 durchgef\u00fchrt. N\u00e4here Infos siehe\u00a0<a href=\"https:\/\/www.schulsportinfo.at\">https:\/\/www.schulsportinfo.at<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a  href=\"http:\/\/nmsernstbrunn.ac.at\/wordpress\/wp-content\/uploads\/2017\/11\/gsImgGold.jpg\" data-rel=\"lightbox-gallery-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2770 aligncenter\" src=\"http:\/\/nmsernstbrunn.ac.at\/wordpress\/wp-content\/uploads\/2017\/11\/gsImgGold.jpg\" alt=\"\" width=\"389\" height=\"396\" srcset=\"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-content\/uploads\/2017\/11\/gsImgGold.jpg 262w, https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-content\/uploads\/2017\/11\/gsImgGold-45x45.jpg 45w\" sizes=\"auto, (max-width: 389px) 100vw, 389px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gro\u00dfe Ehre f\u00fcr die N\u00d6 \u00d6ko Mittelschule Ernstbrunn! Unsere Schule wurde vor kurzem mit dem Schulsportg\u00fctesiegel in Gold ausgezeichnet. Die Bem\u00fchungen im Bereich des Schulsports (Sommersportwochen, Wintersportwochen, Schwimmwoche, Ski4school-Tage, Tage des Sports, Volleyball, Fu\u00dfball, Fu\u00dfball-M\u00e4dchen, alle Aktivit\u00e4ten im Bewegungs- und Sportunterricht \u2013 Kletterpark, Eislaufen, Nordic Walking,\u2026..) haben somit eine verdiente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2770,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[31],"class_list":["post-2771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archiv-2017-18","tag-auszeichnung"],"_links":{"self":[{"href":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-json\/wp\/v2\/posts\/2771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-json\/wp\/v2\/comments?post=2771"}],"version-history":[{"count":4,"href":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-json\/wp\/v2\/posts\/2771\/revisions"}],"predecessor-version":[{"id":2775,"href":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-json\/wp\/v2\/posts\/2771\/revisions\/2775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-json\/wp\/v2\/media\/2770"}],"wp:attachment":[{"href":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-json\/wp\/v2\/media?parent=2771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-json\/wp\/v2\/categories?post=2771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schule.nmsernstbrunn.ac.at\/wordpress\/wp-json\/wp\/v2\/tags?post=2771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}